{"id":991696,"date":"2023-08-25T21:31:00","date_gmt":"2023-08-25T19:31:00","guid":{"rendered":"https:\/\/rotim.hr\/?p=991696"},"modified":"2023-12-01T23:24:37","modified_gmt":"2023-12-01T22:24:37","slug":"prof-dottorato-di-ricerca-boris-bozic-md-specialista-in-neurochirurgia","status":"publish","type":"post","link":"https:\/\/rotim.hr\/it\/2023\/08\/25\/prof-dottorato-di-ricerca-boris-bozic-md-specialista-in-neurochirurgia\/","title":{"rendered":"prof. dottorato di ricerca Boris Bo\u017ei\u0107, MD, specialista in neurochirurgia"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<p>Membro della European Association for Pediatric Neurosurgery (ESPN), della European Neurosurgical Association (EANS), della World Neurosurgical Association (WFNS) e della New York Academy, class for biomedical sciences, membro della Euroacademia multidisciplinaria neurotramatologica dal 2017, dal 2022. \u00e8 membro dell&#8217;American Academy of Arts della Bosnia-Erzegovina.<\/p>\n\n\n\n<p>Boris Bo\u017ei\u0107, nato il 21 settembre 1956 a Vares. Laureato nel 1983 presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Sarajevo. Dimostratore di anatomia durante i suoi studi. Ha iniziato la specializzazione in neurochirurgia presso la Clinica di Neurochirurgia dell&#8217;Ospedale Clinico &#8220;Sisters of Mercy&#8221; nel 1987, superando l&#8217;esame di specializzazione nel 1992.<\/p>\n\n\n\n<p>Ora capo del Policlinico della Clinica di Neurochirurgia. Ha difeso la sua tesi di master &#8220;Effetto dell&#8217;iperosmolarit\u00e0 del liquido cerebrospinale sulla pressione intracranica&#8221; presso la Facolt\u00e0 di Scienze e Matematica dell&#8217;Universit\u00e0 di Zagabria nel 1991, e ha conseguito il titolo accademico di Master in Scienze Naturali nel campo della biologia (biomedicina). Ha difeso la sua tesi di dottorato &#8220;Indagine sul comportamento della colonna lombare in condizioni dinamiche&#8221; nel 1995 e ha conseguito il titolo accademico di dottore in scienze biomediche nel campo della medicina nel titolo di associato scientifico nel campo scientifico delle scienze biomediche e salute pubblica.<\/p>\n\n\n\n<p>\u00c8 in corso il processo di selezione per la posizione di Senior Scientific Associate presso la Facolt\u00e0 di Medicina. a Zagabria. Dal 2002 partecipa saltuariamente all&#8217;insegnamento presso il corso post-laurea in medicina fisica e riabilitazione presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Zagabria. Per molti anni ha collaborato tenendo esercitazioni e seminari nel campo della neurochirurgia per la materia Chirurgia Generale e di Guerra con gli studenti della Facolt\u00e0 di Odontoiatria dell&#8217;Universit\u00e0 di Zagabria.<\/p>\n\n\n\n<p>\u00c8 stato eletto al titolo di primarius nel 2005. Dal 2007 insegna presso la Facolt\u00e0 di Kinesiologia presso il Dipartimento di Biomeccanica e dal 2012. in materia di gerontochinesiologia. Dal 2008 partecipa all&#8217;insegnamento presso l&#8217;Universit\u00e0 di scienze della salute di Zagabria, nel campo della biomedicina e delle neuroscienze, e dal 2014. e per l&#8217;insegnamento della materia di anatomia Dal 2014. dal 2010 \u00e8 stato eletto al posto di insegnamento del titolo di professore universitario nel campo della biomedicina e della sanit\u00e0, il campo delle scienze mediche di base ramo dell&#8217;anatomia. partecipa all&#8217;insegnamento presso il Politecnico di Velika Gorica presso il Dipartimento di Anatomia e Fisiologia, e dal 2011 \u00e8 stato eletto alla cattedra titolare di professore universitario nel campo scientifico della biomedicina e della salute, branca dell&#8217;anatomia.Dal 2018 \u00e8 stato eletto al titolo di professore universitario a tempo indeterminato.Nel 2015. \u00e8 stato eletto professore assistente presso la Facolt\u00e0 di Kinesiologia dell&#8217;Universit\u00e0 di Zagabria per il corso di biomeccanica e il corso di gerontokinesiologia, presso la stessa facolt\u00e0 partecipa all&#8217;erogazione degli studi universitari, post-laurea e di dottorato presso la Facolt\u00e0 di Kinesiologia dell&#8217;Universit\u00e0 di Zagabria.<\/p>\n\n\n\n<p>Dal 2017 insegna presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Zagabria, studiando in inglese nell&#8217;ambito del corso di locomozione umana. Nell&#8217;ambito dell&#8217;insegnamento post-laurea, partecipa all&#8217;insegnamento della stessa materia presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Mostar, e al corso di anatomia e biomeccanica del rachide lombare.Ha collaborato a quattro progetti di ricerca scientifica sostenuti dal Ministero di Scienza e Tecnologia della Repubblica di Croazia Zagabria Ha partecipato a numerosi incontri formativi all&#8217;estero organizzati dalla Societ\u00e0 Europea di Neurochirurgia Pediatrica (ESPN) nel 1996 in Austria, nel 1997 in Germania e nel 1998 in Italia Ha partecipato a numerosi eventi scientifici e incontri professionali.<\/p>\n\n\n\n<p>Come membro del comitato organizzatore, ha partecipato attivamente all&#8217;organizzazione del Terzo Congresso Croato di Neurochirurgia nel giugno 2002, e all&#8217;organizzazione del IX Congresso di Chirurgia Endoscopica a Osijek nel 2008, all&#8217;organizzazione dell&#8217;11\u00b0 Congresso di Chirurgia Endoscopica Chirurgia in Sl. Brod nel 2012. Ha pubblicato 135 articoli scientifici e professionali e rapporti di congressi su riviste nazionali e straniere.Come coautore, ha partecipato alla creazione di cinque libri peer-reviewed e cinque script di esperti.Dal 2010, ha ha ricoperto la carica di vicepresidente, \u00e8 membro della Societ\u00e0 croata di neuroscienze, della Societ\u00e0 medica cattolica croata e della Societ\u00e0 degli esperti forensi.<\/p>\n\n\n\n<p>\u00c8 uno dei fondatori della SENS &#8211; Association of South-Eastern European Neurosurgeons. Sposato e padre di due figli, durante la Guerra di Patria, come neurochirurgo specializzato, partecip\u00f2 al lavoro degli Ospedali di Guerra di Slavonski Brod e Velika Gorica.E&#8217; un veterano croato e volontario della Guerra di Patria. \u00c8 il destinatario di due carte dell&#8217;Associazione medica croata per il progresso della professione medica.<\/p>\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Membro della European Association for Pediatric Neurosurgery (ESPN), della European Neurosurgical Association (EANS), della World Neurosurgical Association (WFNS) e della New York Academy, class for biomedical sciences, membro della Euroacademia multidisciplinaria neurotramatologica dal 2017, dal 2022. \u00e8 membro dell&#8217;American Academy of Arts della Bosnia-Erzegovina. Boris Bo\u017ei\u0107, nato il 21 settembre 1956 a Vares. Laureato nel&#8230;<\/p>\n","protected":false},"author":4,"featured_media":990316,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,89],"tags":[],"class_list":["post-991696","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-nostro-team","category-neurochirurgia"],"_links":{"self":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/comments?post=991696"}],"version-history":[{"count":0,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991696\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media\/990316"}],"wp:attachment":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media?parent=991696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/categories?post=991696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/tags?post=991696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}