{"id":991746,"date":"2023-08-17T21:34:00","date_gmt":"2023-08-17T19:34:00","guid":{"rendered":"https:\/\/rotim.hr\/?p=991746"},"modified":"2023-12-01T23:49:10","modified_gmt":"2023-12-01T22:49:10","slug":"la-prof-ssa-antonija-krstacic-md-phd-e-specialista-in-neurologia-e-sottospecialista-in-malattie-neuromuscolari","status":"publish","type":"post","link":"https:\/\/rotim.hr\/it\/2023\/08\/17\/la-prof-ssa-antonija-krstacic-md-phd-e-specialista-in-neurologia-e-sottospecialista-in-malattie-neuromuscolari\/","title":{"rendered":"La Prof.ssa Antonija Krsta\u010di\u0107, MD, PhD, \u00e8 specialista in neurologia e sottospecialista in malattie neuromuscolari"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<p>La Prof.ssa Antonija Krsta\u010di\u0107, MD, PhD, \u00e8 specialista in neurologia e sottospecialista in malattie neuromuscolari. \u00c8 autrice e coautrice di una cinquantina di pubblicazioni scientifiche e professionali. \u00c8 membro della Camera medica croata, dell&#8217;Associazione medica croata, della Societ\u00e0 neurologica croata, della Societ\u00e0 croata per le malattie neuromuscolari e l&#8217;elettromioneuografia clinica e dell&#8217;Accademia neurologica europea.<\/p>\n\n\n\n<p>Dopo aver terminato gli studi presso la Facolt\u00e0 di Medicina, ha superato l&#8217;esame di stato nel 2000 a Zagabria. Ha completato la sua specializzazione in neurologia presso la Clinica di Neurologia del KBC &#8220;Rebro&#8221; di Zagabria e ha superato l&#8217;esame specialistico nel 2008. Nel 2007 ha difeso la sua tesi di master &#8220;La relazione tra fattori di rischio e ictus ischemico&#8221; presso la Facolt\u00e0 di Scienze dell&#8217;Universit\u00e0 di Zagabria (relatore Prof. Josipa Kern, Scuola di Sanit\u00e0 Pubblica &#8220;Andrija \u0160tampar&#8221;, Facolt\u00e0 di Medicina, Universit\u00e0 di Zagabria). Dal 2008 lavora come specialista in neurologia nel Laboratorio di Diagnosi e Cura Elettromioneurografica presso la Clinica di Traumatologia, KBC &#8220;Sestre milosrdnice&#8221;. Nel 2011, ha difeso la sua tesi di dottorato &#8220;Variabilit\u00e0 della frequenza cardiaca e modelli predittivi di disfunzione autonomica dopo lesione del midollo spinale cervicale&#8221; presso la Facolt\u00e0 di Scienze dell&#8217;Universit\u00e0 di Zagabria (supervisore del Prof. Gojko Buljat, Clinica di Traumatologia, Facolt\u00e0 di Medicina, Universit\u00e0 di Zagabria). Nel 2018 \u00e8 diventata subspecialista in malattie neuromuscolari nel campo della neurologia. \u00c8 medico di base da aprile 2018. Dal 2020 lavora come Capo del Dipartimento di Neurologia presso la Clinica di Traumatologia, KBC &#8220;Sestre milosrdnice&#8221;.<\/p>\n\n\n\n<p>Impegni universitari<\/p>\n\n\n\n<p>Nel 2016 \u00e8 stata nominata professore associato presso il Dipartimento di Neurologia della Facolt\u00e0 di Medicina e Chirurgia di Osijek. Nel 2019 \u00e8 stata nominata professore associato presso il Dipartimento di Neurologia e Neurochirurgia della Facolt\u00e0 di Odontoiatria e Salute di Osijek presso l&#8217;Universit\u00e0 Josip Juraj Strossmayer di Osijek. Nel 2017 \u00e8 stata nominata senior research associate nel campo della Biomedicina e della Salute, area scientifica delle Scienze Mediche Cliniche presso la Facolt\u00e0 di Medicina di Osijek presso l&#8217;Universit\u00e0 Josip Juraj Strossmayer di Osijek. \u00c8 stata relatrice di una decina di elaborati finali e di due tesi di diploma.<\/p>\n\n\n\n<p>Paternit\u00e0 di un libro<\/p>\n\n\n\n<p>\u00c8 autrice e coautrice di cinque libri di testo. Ha curato il libro &#8220;Surgical Medical Sciences Diagnosis and Treatment&#8221; pubblicato da Livre de Lyon nel 2021. \u00c8 coautrice di diversi capitoli di libri, tra cui Nonlinear Dynamics in Ischemic Heart Disease e Evaluation of cardiac autonomic balance after acute cervical spinal cord lesione e &#8220;Complicanze cardiovascolari dopo lesione cerebrale&#8221; in &#8220;Neurocardiologia&#8221;.<\/p>\n\n\n\n<p>Nel 2018 \u00e8 coautrice di un capitolo sul trattamento odontoiatrico dei pazienti cardiovascolari anziani e di un capitolo sulla cardiologia dello sport nel libro &#8220;Surgical Medical Sciences Diagnosis and Treatment&#8221;.<\/p>\n\n\n\n<p>Da maggio 2018 \u00e8 membro del focus group &#8220;Contemporary and new treatment of muscolosceletal conditions in Bio-thermal Centres&#8221; Association, Croato American Professionals, &#8220;ACAP Medical Tourism Task Force Retreat&#8221;, Washington, DC.<\/p>\n\n\n\n<p>\u00c8 membro del comitato editoriale del Journal of Bioanthropology nel 2021 e del comitato editoriale di &#8220;Current Research in Surgery Medical Sciences&#8221; dal 2019. \u00c8 stata anche membro del comitato organizzatore dell&#8217;International Hippocrates Congress on Medical and Health Scienze a Istanbul 2019, Ankara 2020, Antalya 2020 online, 2021 Turska online.<\/p>\n\n\n\n<p>Partecipa come revisore per Acta Clinica Croatica, Journal of Neuroimaging in Psychiatry and Neurology e Cureus Journal of Medical Science.<\/p>\n\n\n\n<p>Partecipa attivamente a congressi e simposi europei e nazionali con presentazioni orali o poster.<\/p>\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>La Prof.ssa Antonija Krsta\u010di\u0107, MD, PhD, \u00e8 specialista in neurologia e sottospecialista in malattie neuromuscolari. \u00c8 autrice e coautrice di una cinquantina di pubblicazioni scientifiche e professionali. \u00c8 membro della Camera medica croata, dell&#8217;Associazione medica croata, della Societ\u00e0 neurologica croata, della Societ\u00e0 croata per le malattie neuromuscolari e l&#8217;elettromioneuografia clinica e dell&#8217;Accademia neurologica europea. Dopo&#8230;<\/p>\n","protected":false},"author":4,"featured_media":990319,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,114],"tags":[],"class_list":["post-991746","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-nostro-team","category-neurologia"],"_links":{"self":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991746","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/comments?post=991746"}],"version-history":[{"count":0,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991746\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media\/990319"}],"wp:attachment":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media?parent=991746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/categories?post=991746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/tags?post=991746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}