{"id":991856,"date":"2023-12-07T20:00:00","date_gmt":"2023-12-07T19:00:00","guid":{"rendered":"https:\/\/rotim.hr\/?p=991856"},"modified":"2023-12-04T12:50:51","modified_gmt":"2023-12-04T11:50:51","slug":"vladimir-kalousek-md-specialista-in-radiologia-febni","status":"publish","type":"post","link":"https:\/\/rotim.hr\/it\/2023\/12\/07\/vladimir-kalousek-md-specialista-in-radiologia-febni\/","title":{"rendered":"Vladimir Kalousek, MD, specialista in radiologia, FEBNI"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<p>Membro del Comitato europeo per i neurointerventi (EBNI), presidente della sezione dell&#8217;Europa orientale della Societ\u00e0 europea per la terapia neurologica minimamente invasiva.<\/p>\n\n\n\n<p>Percorso professionale<\/p>\n\n\n\n<p>Si \u00e8 laureato presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Zagabria nel 2003, e nel 2004 \u00e8 diventato ricercatore tirocinante presso la Clinica di Chirurgia &#8220;Sisters of Mercy&#8221; per 2 anni, per poi specializzarsi in radiologia, superando l&#8217;esame di specializzazione nel 2010. Subito dopo aver superato l&#8217;esame, inizia le sottospecializzazioni in radiologia interventistica e neuroradiologia. La formazione nel campo della radiologia neurointerventistica inizia all&#8217;estero prima con il prof. Milo\u0161evi\u0107 a Lubiana e poi al prof. Hausegger a Klagenfurt.<\/p>\n\n\n\n<p>Impegni universitari<\/p>\n\n\n\n<p>Nel 2012 ha ricevuto una borsa di studio dal prof. Moreta a Parigi, Ospedale Beaujon. Durante quel periodo, partecipa attivamente al lavoro scientifico ed \u00e8 tra gli altri coautore di una pubblicazione pubblicata sul Journal of neurointerventional surgery: Samaniego EA, Kalousek V, Abdo G, et al. Esperienza preliminare con Precipitating Hydrophobic Injectable Liquid (PHIL) nel trattamento delle MAV cerebrali, presso il British Medical Journal. Inoltre partecipa attivamente a presentazioni congressuali ai pi\u00f9 prestigiosi congressi nel campo del neurointervento (LINNC 2013 ad oggi, ESMINT 2013 ad oggi).<\/p>\n\n\n\n<p>Posizioni professionali<\/p>\n\n\n\n<p>\u00c8 membro della Societ\u00e0 Europea di Terapia Neurologica Minimamente Invasiva (ESMINT), della Societ\u00e0 Croata di Radiologia, vicepresidente della Societ\u00e0 Croata di Chirurgia Endovascolare e Neurovascolare<\/p>\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Membro del Comitato europeo per i neurointerventi (EBNI), presidente della sezione dell&#8217;Europa orientale della Societ\u00e0 europea per la terapia neurologica minimamente invasiva. Percorso professionale Si \u00e8 laureato presso la Facolt\u00e0 di Medicina dell&#8217;Universit\u00e0 di Zagabria nel 2003, e nel 2004 \u00e8 diventato ricercatore tirocinante presso la Clinica di Chirurgia &#8220;Sisters of Mercy&#8221; per 2 anni,&#8230;<\/p>\n","protected":false},"author":4,"featured_media":990283,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[85,113],"tags":[],"class_list":["post-991856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-il-nostro-team","category-radiologia"],"_links":{"self":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/comments?post=991856"}],"version-history":[{"count":0,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/posts\/991856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media\/990283"}],"wp:attachment":[{"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/media?parent=991856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/categories?post=991856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rotim.hr\/it\/wp-json\/wp\/v2\/tags?post=991856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}